{"id":15130,"date":"2023-02-12T16:42:37","date_gmt":"2023-02-12T15:42:37","guid":{"rendered":"https:\/\/max-emden.de\/wordpress\/?p=15130"},"modified":"2023-02-19T17:25:13","modified_gmt":"2023-02-19T16:25:13","slug":"festakt-zum-150-schuljubilaeum","status":"publish","type":"post","link":"https:\/\/max-emden.de\/wordpress\/festakt-zum-150-schuljubilaeum\/","title":{"rendered":"Festakt zum 150. Schuljubil\u00e4um"},"content":{"rendered":"<figure id=\"attachment_15134\" aria-describedby=\"caption-attachment-15134\" style=\"width: 1800px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/2023\/02\/Festakt-150-Jahre-LR-4.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-15134 size-full\" src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/2023\/02\/Festakt-150-Jahre-LR-4.jpg\" alt=\"\" width=\"1800\" height=\"1200\" srcset=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/2023\/02\/Festakt-150-Jahre-LR-4.jpg 1800w, https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/2023\/02\/Festakt-150-Jahre-LR-4-300x200.jpg 300w, https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/2023\/02\/Festakt-150-Jahre-LR-4-1024x683.jpg 1024w, https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/2023\/02\/Festakt-150-Jahre-LR-4-768x512.jpg 768w, https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/2023\/02\/Festakt-150-Jahre-LR-4-1536x1024.jpg 1536w\" sizes=\"(max-width: 1800px) 100vw, 1800px\" \/><\/a><figcaption id=\"caption-attachment-15134\" class=\"wp-caption-text\"><em>Machten den Auftakt &#8211; die Akrobaten der 5e<\/em><\/figcaption><\/figure>\n<p>150 Jahre &#8211;\u00a0 ein besonderes Jubil\u00e4um f\u00fcr unsere Schule, das jetzt mit einem Festakt gefeiert wurde.\u00a0 Knapp zwei Stunden gab es Reden, Musik und Schlaglichter der Schulgeschichte und heutiger Aktivit\u00e4ten, um das zu feiern, was 1872 mit der H\u00f6heren T\u00f6chterschule begann. In der Folge wechselte die Schule mehrfach ihren Namen und ihre Standorte, sodass die Entwicklung von der Kaiserin-Auguste-Viktoria-Lyzeum \u00fcber das Gymnasium am Treckfahrtstief vor allem deutlich zeigt, dass nichts so best\u00e4ndig ist wie der Wandel. Und so steht auch die 2015 erfolgte Umbenennung in Max-Windm\u00fcller-Gymnasium f\u00fcr eine stetige Weiterentwicklung bei Beibehaltung von Traditionen. Dass dies angesichts neuer Herausforderungen nicht so einfach ist, hob auch die nieders\u00e4chsische Kultusministerin Julia Willie Hamburg in ihrem <a href=\"https:\/\/youtu.be\/HvNX_TgvAjU\">Video-Gru\u00dfwort<\/a> hervor. &#8222;Das Max-Windm\u00fcller-Gymnasium schafft das in herausragender Weise&#8220;, betonte Hamburg gleichzeitig und lobte Schulleiter, Kollegium und Sch\u00fclerschaft daf\u00fcr, das Gymnasium immer wieder mit Leben zu f\u00fcllen.<\/p>\n<figure id=\"attachment_15136\" aria-describedby=\"caption-attachment-15136\" style=\"width: 1800px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/2023\/02\/Festakt-150-Jahre-LR-7.jpg\"><img decoding=\"async\" class=\"wp-image-15136 size-full\" src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/2023\/02\/Festakt-150-Jahre-LR-7.jpg\" alt=\"\" width=\"1800\" height=\"1200\" srcset=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/2023\/02\/Festakt-150-Jahre-LR-7.jpg 1800w, https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/2023\/02\/Festakt-150-Jahre-LR-7-300x200.jpg 300w, https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/2023\/02\/Festakt-150-Jahre-LR-7-1024x683.jpg 1024w, https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/2023\/02\/Festakt-150-Jahre-LR-7-768x512.jpg 768w, https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/2023\/02\/Festakt-150-Jahre-LR-7-1536x1024.jpg 1536w\" sizes=\"(max-width: 1800px) 100vw, 1800px\" \/><\/a><figcaption id=\"caption-attachment-15136\" class=\"wp-caption-text\"><em>Freute sich \u00fcber die zahlreichen G\u00e4ste: Schulleiter Frank Tapper<\/em><\/figcaption><\/figure>\n<p>Davon gab es eine Menge zu sehen: Nach einem Auftakt mit akrobatischen Einlagen der 5e folgten Kostproben aus Projekten und AGs, um einen Einblick in die Vielfalt des heutigen Schullebens zu geben. Von der historischen Physik- und der Imker-AG ging es \u00fcber Wirtschaft zum Anfassen zu Innovationen der Schule auf dem Feld der Nachhaltigkeit wie der Etablierung eines Klimarates und Klimaparlamentes, die heute von immer mehr Nachahmer finden. Zudem gab es eine Vorstellung der vielen UNESCO-Aktivit\u00e4ten und internationalen Projekte und Partnerschaften, an denen das Max mitwirkt. Garniert wurde der Festakt mit Anekdoten aus der Fr\u00fchzeit der H\u00f6heren T\u00f6chterschule und einem szenischen Spiel zur Schulgeschichte &#8211; und nat\u00fcrlich ganz viel Musik von diversen Solisten \u00fcber die Schulband bis hin zum Chor aus Eltern, Lehrer:innen und Sch\u00fcler:innen.<\/p>\n<figure id=\"attachment_15137\" aria-describedby=\"caption-attachment-15137\" style=\"width: 1800px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/2023\/02\/Festakt-150-Jahre-LR-13.jpg\"><img decoding=\"async\" class=\"wp-image-15137 size-full\" src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/2023\/02\/Festakt-150-Jahre-LR-13.jpg\" alt=\"\" width=\"1800\" height=\"1200\" srcset=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/2023\/02\/Festakt-150-Jahre-LR-13.jpg 1800w, https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/2023\/02\/Festakt-150-Jahre-LR-13-300x200.jpg 300w, https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/2023\/02\/Festakt-150-Jahre-LR-13-1024x683.jpg 1024w, https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/2023\/02\/Festakt-150-Jahre-LR-13-768x512.jpg 768w, https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/2023\/02\/Festakt-150-Jahre-LR-13-1536x1024.jpg 1536w\" sizes=\"(max-width: 1800px) 100vw, 1800px\" \/><\/a><figcaption id=\"caption-attachment-15137\" class=\"wp-caption-text\"><em>Viele Projekte und AGs stellten sich vor &#8211; auch die Imker<\/em><\/figcaption><\/figure>\n<p>Zu den zahlreichen G\u00e4sten, die das Max in den vergangenen Jahren begleitet und unterst\u00fctzt haben, geh\u00f6rte auch Albrecht Weinberg, der in Begleitung von Gerda D\u00e4nekas gekommen war. Der 97-j\u00e4hrige Holocaust\u00fcberlebende, der zuletzt das deutsch-israelische Projekt &#8222;Keep the memory alive!&#8220; unterst\u00fctzt hat, sorgte auch f\u00fcr besondere Freude bei Oberb\u00fcrgermeister Tim Kruithoff, der Weinberg vor allem w\u00e4hrend der Feierlichkeiten zum 100. Geburtstag Max Windm\u00fcllers im Jahr 2020 kennengelernt hatte.<\/p>\n<figure id=\"attachment_15135\" aria-describedby=\"caption-attachment-15135\" style=\"width: 1800px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/2023\/02\/Festakt-150-Jahre-LR-9.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-15135 size-full\" src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/2023\/02\/Festakt-150-Jahre-LR-9.jpg\" alt=\"\" width=\"1800\" height=\"1200\" srcset=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/2023\/02\/Festakt-150-Jahre-LR-9.jpg 1800w, https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/2023\/02\/Festakt-150-Jahre-LR-9-300x200.jpg 300w, https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/2023\/02\/Festakt-150-Jahre-LR-9-1024x683.jpg 1024w, https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/2023\/02\/Festakt-150-Jahre-LR-9-768x512.jpg 768w, https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/2023\/02\/Festakt-150-Jahre-LR-9-1536x1024.jpg 1536w\" sizes=\"(max-width: 1800px) 100vw, 1800px\" \/><\/a><figcaption id=\"caption-attachment-15135\" class=\"wp-caption-text\"><em>Zollte Lob und Anerkennung f\u00fcr das Max: Oberb\u00fcrgermeister Tim Kruithoff<\/em><\/figcaption><\/figure>\n<p>&#8222;Das Max ist unverzichtbar f\u00fcr die Bildungslandschaft in der Region und unserer Seehafenstadt&#8220;, betonte Kruithoff in seiner Rede, die mit guten W\u00fcnschen f\u00fcr die Zukunft endete: &#8222;Auch f\u00fcr die kommenden &#8211; mindestens 150 Jahre &#8211; w\u00fcnsche ich uns allen alles Gute und die Entdeckung all unserer Talente.&#8220;<\/p>\n<p>Mit der gemeinsam gesungenen Ode an die Freude endete ein Festakt, der gleichzeitig den Auftakt zu weiteren Festveranstaltungen bildet. Im April geht es mit einem Projekt- und Referententag zum Jubil\u00e4um weiter!<\/p>\n<style id=\"bwg-style-0\">    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails {      width: 904px;              justify-content: center;        margin:0 auto !important;              background-color: rgba(255, 255, 255, 0.00);            padding-left: 4px;      padding-top: 4px;      max-width: 100%;            }        #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item {    justify-content: flex-start;      max-width: 180px;            width: 180px !important;          }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item a {       margin-right: 4px;       margin-bottom: 4px;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item0 {      padding: 0px;            background-color:rgba(255,255,255, 0.30);      border: 0px none #CCCCCC;      opacity: 1.00;      border-radius: 0;      box-shadow: 0px 0px 0px #888888;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item1 img {      max-height: none;      max-width: none;      padding: 0 !important;    }        @media only screen and (min-width: 480px) {      #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item0 {        transition: all 0.3s ease 0s;-webkit-transition: all 0.3s ease 0s;      }      #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item0:hover {        -ms-transform: scale(1.1);        -webkit-transform: scale(1.1);        transform: scale(1.1);      }    }          #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item1 {      padding-top: 50%;    }        #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-title2,    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-ecommerce2 {      color: #CCCCCC;      font-family: segoe ui;      font-size: 16px;      font-weight: bold;      padding: 2px;      text-shadow: 0px 0px 0px #888888;      max-height: 100%;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-thumb-description span {    color: #323A45;    font-family: Ubuntu;    font-size: 12px;    max-height: 100%;    word-wrap: break-word;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-play-icon2 {      font-size: 32px;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-ecommerce2 {      font-size: 19.2px;      color: #CCCCCC;    }    <\/style>    <div id=\"bwg_container1_0\"         class=\"bwg_container bwg_thumbnail bwg_thumbnails \"         data-right-click-protection=\"1\"         data-bwg=\"0\"         data-scroll=\"0\"         data-gallery-type=\"thumbnails\"         data-gallery-view-type=\"thumbnails\"         data-current-url=\"\/wordpress\/wp-json\/wp\/v2\/posts\/15130\"         data-lightbox-url=\"https:\/\/max-emden.de\/wordpress\/wp-admin\/admin-ajax.php?action=GalleryBox&#038;current_view=0&#038;gallery_id=381&#038;tag=0&#038;theme_id=1&#038;shortcode_id=787&#038;sort_by=order&#038;order_by=asc&#038;current_url=%2Fwordpress%2Fwp-json%2Fwp%2Fv2%2Fposts%2F15130\"         data-gallery-id=\"381\"         data-popup-width=\"800\"         data-popup-height=\"500\"         data-is-album=\"gallery\"         data-buttons-position=\"bottom\">      <div id=\"bwg_container2_0\">             <div id=\"ajax_loading_0\" class=\"bwg_loading_div_1\">      <div class=\"bwg_loading_div_2\">        <div class=\"bwg_loading_div_3\">          <div id=\"loading_div_0\" class=\"bwg_spider_ajax_loading\">          <\/div>        <\/div>      <\/div>    <\/div>            <form id=\"gal_front_form_0\"              class=\"bwg-hidden\"              method=\"post\"              action=\"#\"              data-current=\"0\"              data-shortcode-id=\"787\"              data-gallery-type=\"thumbnails\"              data-gallery-id=\"381\"              data-tag=\"0\"              data-album-id=\"0\"              data-theme-id=\"1\"              data-ajax-url=\"https:\/\/max-emden.de\/wordpress\/wp-admin\/admin-ajax.php?action=bwg_frontend_data\">          <div id=\"bwg_container3_0\" class=\"bwg-background bwg-background-0\">                <div data-max-count=\"5\"         data-thumbnail-width=\"180\"         data-bwg=\"0\"         data-gallery-id=\"381\"         data-lightbox-url=\"https:\/\/max-emden.de\/wordpress\/wp-admin\/admin-ajax.php?action=GalleryBox&amp;current_view=0&amp;gallery_id=381&amp;tag=0&amp;theme_id=1&amp;shortcode_id=787&amp;sort_by=order&amp;order_by=asc&amp;current_url=%2Fwordpress%2Fwp-json%2Fwp%2Fv2%2Fposts%2F15130\"         id=\"bwg_thumbnails_0\"         class=\"bwg-container-0 bwg-thumbnails bwg-standard-thumbnails bwg-container bwg-border-box\">            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7088\" href=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Festakt-150-Jahre-LR-37.jpg?bwg=1676055865\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7088\"                   data-width=\"300\"                   data-height=\"200\"                   data-src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/thumb\/Festakt-150-Jahre-LR-37.jpg?bwg=1676055865\"                   src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/thumb\/Festakt-150-Jahre-LR-37.jpg?bwg=1676055865\"                   alt=\"Festakt-150-Jahre-LR-37\"                   title=\"Festakt-150-Jahre-LR-37\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7089\" href=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Festakt-150-Jahre-LR-39.jpg?bwg=1676055865\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7089\"                   data-width=\"300\"                   data-height=\"200\"                   data-src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/thumb\/Festakt-150-Jahre-LR-39.jpg?bwg=1676055865\"                   src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/thumb\/Festakt-150-Jahre-LR-39.jpg?bwg=1676055865\"                   alt=\"Festakt-150-Jahre-LR-39\"                   title=\"Festakt-150-Jahre-LR-39\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7090\" href=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Festakt-150-Jahre-LR-38.jpg?bwg=1676055865\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7090\"                   data-width=\"300\"                   data-height=\"200\"                   data-src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/thumb\/Festakt-150-Jahre-LR-38.jpg?bwg=1676055865\"                   src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/thumb\/Festakt-150-Jahre-LR-38.jpg?bwg=1676055865\"                   alt=\"Festakt-150-Jahre-LR-38\"                   title=\"Festakt-150-Jahre-LR-38\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7091\" href=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Festakt-150-Jahre-LR-36.jpg?bwg=1676055865\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7091\"                   data-width=\"300\"                   data-height=\"200\"                   data-src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/thumb\/Festakt-150-Jahre-LR-36.jpg?bwg=1676055865\"                   src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/thumb\/Festakt-150-Jahre-LR-36.jpg?bwg=1676055865\"                   alt=\"Festakt-150-Jahre-LR-36\"                   title=\"Festakt-150-Jahre-LR-36\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7092\" href=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Festakt-150-Jahre-LR-35.jpg?bwg=1676055865\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7092\"                   data-width=\"300\"                   data-height=\"200\"                   data-src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/thumb\/Festakt-150-Jahre-LR-35.jpg?bwg=1676055865\"                   src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/thumb\/Festakt-150-Jahre-LR-35.jpg?bwg=1676055865\"                   alt=\"Festakt-150-Jahre-LR-35\"                   title=\"Festakt-150-Jahre-LR-35\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7093\" href=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Festakt-150-Jahre-LR-40.jpg?bwg=1676055865\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7093\"                   data-width=\"300\"                   data-height=\"200\"                   data-src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/thumb\/Festakt-150-Jahre-LR-40.jpg?bwg=1676055865\"                   src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/thumb\/Festakt-150-Jahre-LR-40.jpg?bwg=1676055865\"                   alt=\"Festakt-150-Jahre-LR-40\"                   title=\"Festakt-150-Jahre-LR-40\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7094\" href=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Festakt-150-Jahre-LR-41.jpg?bwg=1676055865\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7094\"                   data-width=\"300\"                   data-height=\"200\"                   data-src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/thumb\/Festakt-150-Jahre-LR-41.jpg?bwg=1676055865\"                   src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/thumb\/Festakt-150-Jahre-LR-41.jpg?bwg=1676055865\"                   alt=\"Festakt-150-Jahre-LR-41\"                   title=\"Festakt-150-Jahre-LR-41\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7095\" href=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Festakt-150-Jahre-LR-42.jpg?bwg=1676055865\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7095\"                   data-width=\"300\"                   data-height=\"200\"                   data-src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/thumb\/Festakt-150-Jahre-LR-42.jpg?bwg=1676055865\"                   src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/thumb\/Festakt-150-Jahre-LR-42.jpg?bwg=1676055865\"                   alt=\"Festakt-150-Jahre-LR-42\"                   title=\"Festakt-150-Jahre-LR-42\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7096\" href=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Festakt-150-Jahre-LR-43.jpg?bwg=1676055865\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7096\"                   data-width=\"300\"                   data-height=\"200\"                   data-src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/thumb\/Festakt-150-Jahre-LR-43.jpg?bwg=1676055865\"                   src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/thumb\/Festakt-150-Jahre-LR-43.jpg?bwg=1676055865\"                   alt=\"Festakt-150-Jahre-LR-43\"                   title=\"Festakt-150-Jahre-LR-43\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7097\" href=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Festakt-150-Jahre-LR-44.jpg?bwg=1676055865\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7097\"                   data-width=\"300\"                   data-height=\"169\"                   data-src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/thumb\/Festakt-150-Jahre-LR-44.jpg?bwg=1676055865\"                   src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/thumb\/Festakt-150-Jahre-LR-44.jpg?bwg=1676055865\"                   alt=\"Festakt-150-Jahre-LR-44\"                   title=\"Festakt-150-Jahre-LR-44\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7098\" href=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Festakt-150-Jahre-LR-47.jpg?bwg=1676055865\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7098\"                   data-width=\"300\"                   data-height=\"200\"                   data-src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/thumb\/Festakt-150-Jahre-LR-47.jpg?bwg=1676055865\"                   src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/thumb\/Festakt-150-Jahre-LR-47.jpg?bwg=1676055865\"                   alt=\"Festakt-150-Jahre-LR-47\"                   title=\"Festakt-150-Jahre-LR-47\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7099\" href=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Festakt-150-Jahre-LR-45.jpg?bwg=1676055865\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7099\"                   data-width=\"300\"                   data-height=\"200\"                   data-src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/thumb\/Festakt-150-Jahre-LR-45.jpg?bwg=1676055865\"                   src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/thumb\/Festakt-150-Jahre-LR-45.jpg?bwg=1676055865\"                   alt=\"Festakt-150-Jahre-LR-45\"                   title=\"Festakt-150-Jahre-LR-45\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7100\" href=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Festakt-150-Jahre-LR-49.jpg?bwg=1676055865\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7100\"                   data-width=\"300\"                   data-height=\"200\"                   data-src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/thumb\/Festakt-150-Jahre-LR-49.jpg?bwg=1676055865\"                   src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/thumb\/Festakt-150-Jahre-LR-49.jpg?bwg=1676055865\"                   alt=\"Festakt-150-Jahre-LR-49\"                   title=\"Festakt-150-Jahre-LR-49\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7101\" href=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Festakt-150-Jahre-LR-46.jpg?bwg=1676055865\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7101\"                   data-width=\"300\"                   data-height=\"200\"                   data-src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/thumb\/Festakt-150-Jahre-LR-46.jpg?bwg=1676055865\"                   src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/thumb\/Festakt-150-Jahre-LR-46.jpg?bwg=1676055865\"                   alt=\"Festakt-150-Jahre-LR-46\"                   title=\"Festakt-150-Jahre-LR-46\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7102\" href=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Festakt-150-Jahre-LR-48.jpg?bwg=1676055865\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7102\"                   data-width=\"300\"                   data-height=\"200\"                   data-src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/thumb\/Festakt-150-Jahre-LR-48.jpg?bwg=1676055865\"                   src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/thumb\/Festakt-150-Jahre-LR-48.jpg?bwg=1676055865\"                   alt=\"Festakt-150-Jahre-LR-48\"                   title=\"Festakt-150-Jahre-LR-48\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7103\" href=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Festakt-150-Jahre-LR-50.jpg?bwg=1676055865\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7103\"                   data-width=\"300\"                   data-height=\"200\"                   data-src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/thumb\/Festakt-150-Jahre-LR-50.jpg?bwg=1676055865\"                   src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/thumb\/Festakt-150-Jahre-LR-50.jpg?bwg=1676055865\"                   alt=\"Festakt-150-Jahre-LR-50\"                   title=\"Festakt-150-Jahre-LR-50\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7104\" href=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Festakt-150-Jahre-LR-51.jpg?bwg=1676055865\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7104\"                   data-width=\"300\"                   data-height=\"200\"                   data-src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/thumb\/Festakt-150-Jahre-LR-51.jpg?bwg=1676055865\"                   src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/thumb\/Festakt-150-Jahre-LR-51.jpg?bwg=1676055865\"                   alt=\"Festakt-150-Jahre-LR-51\"                   title=\"Festakt-150-Jahre-LR-51\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7105\" href=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Festakt-150-Jahre-LR-53.jpg?bwg=1676055865\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7105\"                   data-width=\"300\"                   data-height=\"200\"                   data-src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/thumb\/Festakt-150-Jahre-LR-53.jpg?bwg=1676055865\"                   src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/thumb\/Festakt-150-Jahre-LR-53.jpg?bwg=1676055865\"                   alt=\"Festakt-150-Jahre-LR-53\"                   title=\"Festakt-150-Jahre-LR-53\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7106\" href=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Festakt-150-Jahre-LR-52.jpg?bwg=1676055865\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7106\"                   data-width=\"300\"                   data-height=\"200\"                   data-src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/thumb\/Festakt-150-Jahre-LR-52.jpg?bwg=1676055865\"                   src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/thumb\/Festakt-150-Jahre-LR-52.jpg?bwg=1676055865\"                   alt=\"Festakt-150-Jahre-LR-52\"                   title=\"Festakt-150-Jahre-LR-52\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7107\" href=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Festakt-150-Jahre-LR-54.jpg?bwg=1676055865\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7107\"                   data-width=\"300\"                   data-height=\"200\"                   data-src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/thumb\/Festakt-150-Jahre-LR-54.jpg?bwg=1676055865\"                   src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/thumb\/Festakt-150-Jahre-LR-54.jpg?bwg=1676055865\"                   alt=\"Festakt-150-Jahre-LR-54\"                   title=\"Festakt-150-Jahre-LR-54\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7108\" href=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Festakt-150-Jahre-LR-55.jpg?bwg=1676055865\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7108\"                   data-width=\"300\"                   data-height=\"200\"                   data-src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/thumb\/Festakt-150-Jahre-LR-55.jpg?bwg=1676055865\"                   src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/thumb\/Festakt-150-Jahre-LR-55.jpg?bwg=1676055865\"                   alt=\"Festakt-150-Jahre-LR-55\"                   title=\"Festakt-150-Jahre-LR-55\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7109\" href=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Festakt-150-Jahre-LR-2.jpg?bwg=1676055865\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7109\"                   data-width=\"300\"                   data-height=\"200\"                   data-src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/thumb\/Festakt-150-Jahre-LR-2.jpg?bwg=1676055865\"                   src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/thumb\/Festakt-150-Jahre-LR-2.jpg?bwg=1676055865\"                   alt=\"Festakt-150-Jahre-LR-2\"                   title=\"Festakt-150-Jahre-LR-2\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7110\" href=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Festakt-150-Jahre-LR-4.jpg?bwg=1676055865\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7110\"                   data-width=\"300\"                   data-height=\"200\"                   data-src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/thumb\/Festakt-150-Jahre-LR-4.jpg?bwg=1676055865\"                   src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/thumb\/Festakt-150-Jahre-LR-4.jpg?bwg=1676055865\"                   alt=\"Festakt-150-Jahre-LR-4\"                   title=\"Festakt-150-Jahre-LR-4\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7111\" href=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Festakt-150-Jahre-LR-1.jpg?bwg=1676055865\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7111\"                   data-width=\"300\"                   data-height=\"200\"                   data-src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/thumb\/Festakt-150-Jahre-LR-1.jpg?bwg=1676055865\"                   src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/thumb\/Festakt-150-Jahre-LR-1.jpg?bwg=1676055865\"                   alt=\"Festakt-150-Jahre-LR-1\"                   title=\"Festakt-150-Jahre-LR-1\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7112\" href=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Festakt-150-Jahre-LR-3.jpg?bwg=1676055865\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7112\"                   data-width=\"300\"                   data-height=\"200\"                   data-src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/thumb\/Festakt-150-Jahre-LR-3.jpg?bwg=1676055865\"                   src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/thumb\/Festakt-150-Jahre-LR-3.jpg?bwg=1676055865\"                   alt=\"Festakt-150-Jahre-LR-3\"                   title=\"Festakt-150-Jahre-LR-3\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7113\" href=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Festakt-150-Jahre-LR-5.jpg?bwg=1676055865\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7113\"                   data-width=\"300\"                   data-height=\"200\"                   data-src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/thumb\/Festakt-150-Jahre-LR-5.jpg?bwg=1676055865\"                   src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/thumb\/Festakt-150-Jahre-LR-5.jpg?bwg=1676055865\"                   alt=\"Festakt-150-Jahre-LR-5\"                   title=\"Festakt-150-Jahre-LR-5\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7114\" href=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Festakt-150-Jahre-LR-7.jpg?bwg=1676055865\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7114\"                   data-width=\"300\"                   data-height=\"200\"                   data-src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/thumb\/Festakt-150-Jahre-LR-7.jpg?bwg=1676055865\"                   src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/thumb\/Festakt-150-Jahre-LR-7.jpg?bwg=1676055865\"                   alt=\"Festakt-150-Jahre-LR-7\"                   title=\"Festakt-150-Jahre-LR-7\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7115\" href=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Festakt-150-Jahre-LR-6.jpg?bwg=1676055865\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7115\"                   data-width=\"300\"                   data-height=\"200\"                   data-src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/thumb\/Festakt-150-Jahre-LR-6.jpg?bwg=1676055865\"                   src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/thumb\/Festakt-150-Jahre-LR-6.jpg?bwg=1676055865\"                   alt=\"Festakt-150-Jahre-LR-6\"                   title=\"Festakt-150-Jahre-LR-6\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7116\" href=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Festakt-150-Jahre-LR-9.jpg?bwg=1676055865\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7116\"                   data-width=\"300\"                   data-height=\"200\"                   data-src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/thumb\/Festakt-150-Jahre-LR-9.jpg?bwg=1676055865\"                   src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/thumb\/Festakt-150-Jahre-LR-9.jpg?bwg=1676055865\"                   alt=\"Festakt-150-Jahre-LR-9\"                   title=\"Festakt-150-Jahre-LR-9\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"7117\" href=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Festakt-150-Jahre-LR-8.jpg?bwg=1676055865\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"7117\"                   data-width=\"300\"                   data-height=\"200\"                   data-src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/thumb\/Festakt-150-Jahre-LR-8.jpg?bwg=1676055865\"                   src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/thumb\/Festakt-150-Jahre-LR-8.jpg?bwg=1676055865\"                   alt=\"Festakt-150-Jahre-LR-8\"                   title=\"Festakt-150-Jahre-LR-8\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>          <\/div>    <style>      \/*pagination styles*\/      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 {\t\t\t\ttext-align: center;\t\t\t\tfont-size: 12px;\t\t\t\tfont-family: segoe ui;\t\t\t\tfont-weight: bold;\t\t\t\tcolor: #666666;\t\t\t\tmargin: 6px 0 4px;\t\t\t\tdisplay: block;      }      @media only screen and (max-width : 320px) {      #bwg_container1_0 #bwg_container2_0 .displaying-num_0 {     \t display: none;      }      }      #bwg_container1_0 #bwg_container2_0 .displaying-num_0 {\t\t\t\tfont-size: 12px;\t\t\t\tfont-family: segoe ui;\t\t\t\tfont-weight: bold;\t\t\t\tcolor: #666666;\t\t\t\tmargin-right: 10px;\t\t\t\tvertical-align: middle;      }      #bwg_container1_0 #bwg_container2_0 .paging-input_0 {\t\t\t\tfont-size: 12px;\t\t\t\tfont-family: segoe ui;\t\t\t\tfont-weight: bold;\t\t\t\tcolor: #666666;\t\t\t\tvertical-align: middle;      }      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 a.disabled,      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 a.disabled:hover,      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 a.disabled:focus,\t\t\t#bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 input.bwg_current_page {\t\t\t\tcursor: default;\t\t\t\tcolor: rgba(102, 102, 102, 0.5);      }      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 a,      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 input.bwg_current_page {\t\t\t\tcursor: pointer;\t\t\t\ttext-align: center;\t\t\t\tfont-size: 12px;\t\t\t\tfont-family: segoe ui;\t\t\t\tfont-weight: bold;\t\t\t\tcolor: #666666;\t\t\t\ttext-decoration: none;\t\t\t\tpadding: 3px 6px;\t\t\t\tmargin: 0;\t\t\t\tborder-radius: 0;\t\t\t\tborder-style: solid;\t\t\t\tborder-width: 1px;\t\t\t\tborder-color: #E3E3E3;\t\t\t\t\t\t\t\tbackground-color: rgba(255, 255, 255, 1.00);\t\t\t\tbox-shadow: 0;\t\t\t\ttransition: all 0.3s ease 0s;-webkit-transition: all 0.3s ease 0s;      }      <\/style>      <span class=\"bwg_nav_cont_0\">              <div class=\"tablenav-pages_0\">                      <span class=\"pagination-links_0 pagination-links\" data-pages-count=\"2\">              <span class=\"pagination-links_col1\">              <a class=\"bwg-a first-page disabled\" title=\"Zur ersten Seite\" >\u00ab<\/a>              <a class=\"bwg-a prev-page disabled\" title=\"Zur vorherigen Seite\" >\u2039<\/a>              <\/span>\t\t\t\t\t\t\t<span class=\"pagination-links_col2\">\t\t\t\t\t\t\t\t\t<input type=\"number\" class=\"bwg_current_page\" name=\"bwg_current_page\" value=\"1\" data-url-info=\"page_number_0\" onkeypress=\"return bwg_change_page_0(event, this)\" min=\"1\" oninput=\"validity.valid||(value='')\" \/>\t\t\t\t\t\t\t\t\t\tvon\t\t\t\t\t\t\t\t\t\t<span class=\"total-pages_0\">\t\t\t\t\t\t\t\t\t\t\t2\t\t\t\t\t\t\t\t\t\t<\/span>\t\t\t\t\t\t\t<\/span>              <span class=\"pagination-links_col3\">                <a class=\"bwg-a next-page-0\" title=\"Zur n\u00e4chsten Seite\" href=\"\/wordpress\/wp-json\/wp\/v2\/posts\/15130?page_number_0=2\">\u203a<\/a>                <a class=\"bwg-a last-page-0\" title=\"Zur letzten Seite\" href=\"\/wordpress\/wp-json\/wp\/v2\/posts\/15130?page_number_0=2\">\u00bb<\/a>              <\/span>\t\t\t\t\t\t<\/span>\t\t\t\t\t\t        <\/div>                <input type=\"hidden\" id=\"page_number_0\" name=\"page_number_0\" value=\"1\" \/>      <script type=\"text\/javascript\">        if( jQuery('.bwg_nav_cont_0').length > 1 ) {          jQuery('.bwg_nav_cont_0').first().remove()        }        function spider_page_0(cur, x, y, load_more) {          if (typeof load_more == \"undefined\") {            var load_more = false;          }          if (jQuery(cur).hasClass('disabled')) {            return false;          }          var items_county_0 = 2;          switch (y) {            case 1:              if (x >= items_county_0) {                document.getElementById('page_number_0').value = items_county_0;              }              else {                document.getElementById('page_number_0').value = x + 1;              }              break;            case 2:              document.getElementById('page_number_0').value = items_county_0;              break;            case -1:              if (x == 1) {                document.getElementById('page_number_0').value = 1;              }              else {                document.getElementById('page_number_0').value = x - 1;              }              break;            case -2:              document.getElementById('page_number_0').value = 1;              break;\t\t\t\t\t\tcase 0:              document.getElementById('page_number_0').value = x;              break;            default:              document.getElementById('page_number_0').value = 1;          }          bwg_ajax('gal_front_form_0', '0', 'bwg_thumbnails_0', '0', '', 'gallery', 0, '', '', load_more, '', 1);        }                    jQuery('.first-page disabled').on('click', function () {              spider_page_0(this, 1, -2, 'numeric');              return false;            });            jQuery('.prev-page disabled').on('click', function () {              spider_page_0(this, 1, -1, 'numeric');              return false;            });            jQuery('.next-page-0').on('click', function () {              spider_page_0(this, 1, 1, 'numeric');              return false;            });            jQuery('.last-page-0').on('click', function () {              spider_page_0(this, 1, 2, 'numeric');              return false;            });        \t\t\t\t\/* Change page on input enter. *\/        function bwg_change_page_0( e, that ) {          if (  e.key == 'Enter' ) {            var to_page = parseInt(jQuery(that).val());            var pages_count = jQuery(that).parents(\".pagination-links\").data(\"pages-count\");            var current_url_param = jQuery(that).attr('data-url-info');            if (to_page > pages_count) {              to_page = 1;            }\t \t\t\t\t\t\t\t\t\t\t\t\tspider_page_0(this, to_page, 0, 'numeric');\t\t\t\t\t\t\treturn false;\t\t\t\t\t\t          }          return true;        }        jQuery('.bwg_load_btn_0').on('click', function () {            spider_page_0(this, 1, 1, true);            return false;        });      <\/script>      <\/span>                <\/div>        <\/form>        <style>          #bwg_container1_0 #bwg_container2_0 #spider_popup_overlay_0 {          background-color: #000000;          opacity: 0.70;          }          <\/style>        <div id=\"bwg_spider_popup_loading_0\" class=\"bwg_spider_popup_loading\"><\/div>        <div id=\"spider_popup_overlay_0\" class=\"spider_popup_overlay\" onclick=\"spider_destroypopup(1000)\"><\/div>        <input type=\"hidden\" id=\"bwg_random_seed_0\" value=\"608180499\">                <\/div>    <\/div>    <script>      if (document.readyState === 'complete') {        if( typeof bwg_main_ready == 'function' ) {          if ( jQuery(\"#bwg_container1_0\").height() ) {            bwg_main_ready(jQuery(\"#bwg_container1_0\"));          }        }      } else {        document.addEventListener('DOMContentLoaded', function() {          if( typeof bwg_main_ready == 'function' ) {            if ( jQuery(\"#bwg_container1_0\").height() ) {             bwg_main_ready(jQuery(\"#bwg_container1_0\"));            }          }        });      }    <\/script>    \n","protected":false},"excerpt":{"rendered":"<p>150 Jahre &#8211;\u00a0 ein besonderes Jubil\u00e4um f\u00fcr unsere Schule, das jetzt mit einem Festakt gefeiert wurde.\u00a0 Knapp zwei Stunden gab es Reden, Musik und Schlaglichter<a class=\"moretag\" href=\"https:\/\/max-emden.de\/wordpress\/festakt-zum-150-schuljubilaeum\/\"> [&#8230;]<\/a><\/p>\n","protected":false},"author":3,"featured_media":15134,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[96],"class_list":["post-15130","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","tag-aktuell"],"_links":{"self":[{"href":"https:\/\/max-emden.de\/wordpress\/wp-json\/wp\/v2\/posts\/15130","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/max-emden.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/max-emden.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/max-emden.de\/wordpress\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/max-emden.de\/wordpress\/wp-json\/wp\/v2\/comments?post=15130"}],"version-history":[{"count":8,"href":"https:\/\/max-emden.de\/wordpress\/wp-json\/wp\/v2\/posts\/15130\/revisions"}],"predecessor-version":[{"id":15149,"href":"https:\/\/max-emden.de\/wordpress\/wp-json\/wp\/v2\/posts\/15130\/revisions\/15149"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/max-emden.de\/wordpress\/wp-json\/wp\/v2\/media\/15134"}],"wp:attachment":[{"href":"https:\/\/max-emden.de\/wordpress\/wp-json\/wp\/v2\/media?parent=15130"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/max-emden.de\/wordpress\/wp-json\/wp\/v2\/categories?post=15130"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/max-emden.de\/wordpress\/wp-json\/wp\/v2\/tags?post=15130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}