{"id":3530,"date":"2016-11-23T16:41:25","date_gmt":"2016-11-23T16:41:25","guid":{"rendered":"http:\/\/max-emden.de\/wordpress\/?p=3530"},"modified":"2016-12-03T09:52:44","modified_gmt":"2016-12-03T09:52:44","slug":"giacometti-meets-gips","status":"publish","type":"post","link":"https:\/\/max-emden.de\/wordpress\/giacometti-meets-gips\/","title":{"rendered":"Giacometti meets Gips"},"content":{"rendered":"<p style=\"text-align: justify;\">Nachdem die Sch\u00fclerinnen und Sch\u00fcler der Klassen 7B und 7C den K\u00fcnstler Alberto Giacometti und seine Arbeiten kennenglernt hatten, machten sie sich selbst ans Werk.\u00a0Es sollten zwei Figuren in Beziehung gesetzt werden, die T\u00e4ter und Opfer in einer Mobbing-Situation darstellen. Dabei sollte, \u00e4hnlich wie bei Giacometti, der Ausdruck durch die K\u00f6rperhaltung entstehen und nicht durch die Mimik der Personen.<!--more-->\u00a0Die Materialwahl lie\u00df den Sch\u00fclerinnen und Sch\u00fclern auch gar keine Chance und so werkelten sie geduldig, bis die letzte Alufolien-Figur Gestalt angenommen hatte.<\/p>\n<p style=\"text-align: justify;\">Die anschlie\u00dfende Gipsbearbeitung war eine weitere haptische Erfahrung, die nicht bei allen Sch\u00fclerInnen f\u00fcr Begeisterung sorgte. Letztlich ist aber auch das Anr\u00fchren und Verarbeiten von Gips eine wichtige Kompetenz im sp\u00e4teren Leben \ud83d\ude09<\/p>\n<p style=\"text-align: justify;\">Bei der anschlie\u00dfenden Werkbesprechung, bei der die Ergebnisse der Mitsch\u00fclerInnen als l\u00fcckenlose Absicht pr\u00e4sentiert wurden, kamen viele interessante Deutungen zu Tage. So wurde nach der fantasievollen Beschreibung der m\u00f6glichen Szenarien, dem Durchblitzen der Alufolie, einem Schaschlick-Spie\u00df oder dem Fehlen eines K\u00f6rperteils eine tiefgehende Bedeutung zugesprochen. Ebenso wurden die Beweggr\u00fcnde der T\u00e4ter im Laufe der Interpretationen thematisiert oder es wurde die gesamte urspr\u00fcngliche Rollenverteilung auf den Kopf gestellt.<\/p>\n<p style=\"text-align: justify;\">Und nicht zuletzt war bei genauer Betrachtung oftmals doch eine erkennbare Mimik in den Gipsspuren zu sehen.<\/p>\n<style id=\"bwg-style-0\">    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails {      width: 904px;              justify-content: center;        margin:0 auto !important;              background-color: rgba(255, 255, 255, 0.00);            padding-left: 4px;      padding-top: 4px;      max-width: 100%;            }        #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item {    justify-content: flex-start;      max-width: 180px;            width: 180px !important;          }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item a {       margin-right: 4px;       margin-bottom: 4px;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item0 {      padding: 0px;            background-color:rgba(255,255,255, 0.30);      border: 0px none #CCCCCC;      opacity: 1.00;      border-radius: 0;      box-shadow: 0px 0px 0px #888888;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item1 img {      max-height: none;      max-width: none;      padding: 0 !important;    }        @media only screen and (min-width: 480px) {      #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item0 {        transition: all 0.3s ease 0s;-webkit-transition: all 0.3s ease 0s;      }      #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item0:hover {        -ms-transform: scale(1.1);        -webkit-transform: scale(1.1);        transform: scale(1.1);      }    }          #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item1 {      padding-top: 50%;    }        #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-title2,    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-ecommerce2 {      color: #CCCCCC;      font-family: segoe ui;      font-size: 16px;      font-weight: bold;      padding: 2px;      text-shadow: 0px 0px 0px #888888;      max-height: 100%;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-thumb-description span {    color: #323A45;    font-family: Ubuntu;    font-size: 12px;    max-height: 100%;    word-wrap: break-word;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-play-icon2 {      font-size: 32px;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-ecommerce2 {      font-size: 19.2px;      color: #CCCCCC;    }    <\/style>    <div id=\"bwg_container1_0\"         class=\"bwg_container bwg_thumbnail bwg_thumbnails \"         data-right-click-protection=\"1\"         data-bwg=\"0\"         data-scroll=\"0\"         data-gallery-type=\"thumbnails\"         data-gallery-view-type=\"thumbnails\"         data-current-url=\"\/wordpress\/wp-json\/wp\/v2\/posts\/3530\"         data-lightbox-url=\"https:\/\/max-emden.de\/wordpress\/wp-admin\/admin-ajax.php?action=GalleryBox&#038;current_view=0&#038;gallery_id=96&#038;tag=0&#038;theme_id=1&#038;shortcode_id=103&#038;sort_by=order&#038;order_by=asc&#038;current_url=%2Fwordpress%2Fwp-json%2Fwp%2Fv2%2Fposts%2F3530\"         data-gallery-id=\"96\"         data-popup-width=\"800\"         data-popup-height=\"500\"         data-is-album=\"gallery\"         data-buttons-position=\"bottom\">      <div id=\"bwg_container2_0\">             <div id=\"ajax_loading_0\" class=\"bwg_loading_div_1\">      <div class=\"bwg_loading_div_2\">        <div class=\"bwg_loading_div_3\">          <div id=\"loading_div_0\" class=\"bwg_spider_ajax_loading\">          <\/div>        <\/div>      <\/div>    <\/div>            <form id=\"gal_front_form_0\"              class=\"bwg-hidden\"              method=\"post\"              action=\"#\"              data-current=\"0\"              data-shortcode-id=\"103\"              data-gallery-type=\"thumbnails\"              data-gallery-id=\"96\"              data-tag=\"0\"              data-album-id=\"0\"              data-theme-id=\"1\"              data-ajax-url=\"https:\/\/max-emden.de\/wordpress\/wp-admin\/admin-ajax.php?action=bwg_frontend_data\">          <div id=\"bwg_container3_0\" class=\"bwg-background bwg-background-0\">                <div data-max-count=\"5\"         data-thumbnail-width=\"180\"         data-bwg=\"0\"         data-gallery-id=\"96\"         data-lightbox-url=\"https:\/\/max-emden.de\/wordpress\/wp-admin\/admin-ajax.php?action=GalleryBox&amp;current_view=0&amp;gallery_id=96&amp;tag=0&amp;theme_id=1&amp;shortcode_id=103&amp;sort_by=order&amp;order_by=asc&amp;current_url=%2Fwordpress%2Fwp-json%2Fwp%2Fv2%2Fposts%2F3530\"         id=\"bwg_thumbnails_0\"         class=\"bwg-container-0 bwg-thumbnails bwg-standard-thumbnails bwg-container bwg-border-box\">            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"1986\" href=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/5.JPG\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"1986\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/thumb\/5.JPG\"                   src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/thumb\/5.JPG\"                   alt=\"5\"                   title=\"5\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"1985\" href=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/3.JPG\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"1985\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/thumb\/3.JPG\"                   src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/thumb\/3.JPG\"                   alt=\"3\"                   title=\"3\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"1984\" href=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/6.JPG\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"1984\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/thumb\/6.JPG\"                   src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/thumb\/6.JPG\"                   alt=\"6\"                   title=\"6\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"1983\" href=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/2.JPG\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"1983\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/thumb\/2.JPG\"                   src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/thumb\/2.JPG\"                   alt=\"2\"                   title=\"2\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"1982\" href=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/4.JPG\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"1982\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/thumb\/4.JPG\"                   src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/thumb\/4.JPG\"                   alt=\"4\"                   title=\"4\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"1981\" href=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/1.JPG\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"1981\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/thumb\/1.JPG\"                   src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/thumb\/1.JPG\"                   alt=\"1\"                   title=\"1\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"1980\" href=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/7.JPG\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"1980\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/thumb\/7.JPG\"                   src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/thumb\/7.JPG\"                   alt=\"7\"                   title=\"7\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"1979\" href=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/11.JPG\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"1979\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/thumb\/11.JPG\"                   src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/thumb\/11.JPG\"                   alt=\"11\"                   title=\"11\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"1978\" href=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/10.JPG\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"1978\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/thumb\/10.JPG\"                   src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/thumb\/10.JPG\"                   alt=\"10\"                   title=\"10\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"1977\" href=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/8.JPG\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"1977\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/thumb\/8.JPG\"                   src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/thumb\/8.JPG\"                   alt=\"8\"                   title=\"8\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"1976\" href=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/9.JPG\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"1976\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/thumb\/9.JPG\"                   src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/thumb\/9.JPG\"                   alt=\"9\"                   title=\"9\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"1975\" href=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/17.JPG\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"1975\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/thumb\/17.JPG\"                   src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/thumb\/17.JPG\"                   alt=\"17\"                   title=\"17\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"1974\" href=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/20.JPG\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"1974\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/thumb\/20.JPG\"                   src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/thumb\/20.JPG\"                   alt=\"20\"                   title=\"20\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"1973\" href=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/18.JPG\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"1973\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/thumb\/18.JPG\"                   src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/thumb\/18.JPG\"                   alt=\"18\"                   title=\"18\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"1972\" href=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/13.JPG\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"1972\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/thumb\/13.JPG\"                   src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/thumb\/13.JPG\"                   alt=\"13\"                   title=\"13\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"1971\" href=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/16.JPG\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"1971\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/thumb\/16.JPG\"                   src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/thumb\/16.JPG\"                   alt=\"16\"                   title=\"16\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"1970\" href=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/12.JPG\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"1970\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/thumb\/12.JPG\"                   src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/thumb\/12.JPG\"                   alt=\"12\"                   title=\"12\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"1969\" href=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/14.JPG\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"1969\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/thumb\/14.JPG\"                   src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/thumb\/14.JPG\"                   alt=\"14\"                   title=\"14\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"1968\" href=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/15.JPG\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"1968\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/thumb\/15.JPG\"                   src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/thumb\/15.JPG\"                   alt=\"15\"                   title=\"15\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"1967\" href=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/21.JPG\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"1967\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/thumb\/21.JPG\"                   src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/thumb\/21.JPG\"                   alt=\"21\"                   title=\"21\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"1966\" href=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/22.JPG\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"1966\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/thumb\/22.JPG\"                   src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/thumb\/22.JPG\"                   alt=\"22\"                   title=\"22\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"1965\" href=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/19.JPG\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"1965\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/thumb\/19.JPG\"                   src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/thumb\/19.JPG\"                   alt=\"19\"                   title=\"19\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"1964\" href=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/25.JPG\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"1964\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/thumb\/25.JPG\"                   src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/thumb\/25.JPG\"                   alt=\"25\"                   title=\"25\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"1963\" href=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/27.JPG\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"1963\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/thumb\/27.JPG\"                   src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/thumb\/27.JPG\"                   alt=\"27\"                   title=\"27\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"1962\" href=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/26.JPG\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"1962\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/thumb\/26.JPG\"                   src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/thumb\/26.JPG\"                   alt=\"26\"                   title=\"26\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"1961\" href=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/23.JPG\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"1961\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/thumb\/23.JPG\"                   src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/thumb\/23.JPG\"                   alt=\"23\"                   title=\"23\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"1960\" href=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/24.JPG\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"1960\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/thumb\/24.JPG\"                   src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/thumb\/24.JPG\"                   alt=\"24\"                   title=\"24\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"1959\" href=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/31.JPG\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"1959\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/thumb\/31.JPG\"                   src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/thumb\/31.JPG\"                   alt=\"31\"                   title=\"31\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"1958\" href=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/30.JPG\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"1958\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/thumb\/30.JPG\"                   src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/thumb\/30.JPG\"                   alt=\"30\"                   title=\"30\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"1957\" href=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/29.JPG\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"1957\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/thumb\/29.JPG\"                   src=\"https:\/\/max-emden.de\/wordpress\/wp-content\/uploads\/photo-gallery\/Kunst\/Giacometti\/thumb\/29.JPG\"                   alt=\"29\"                   title=\"29\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>          <\/div>    <style>      \/*pagination styles*\/      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 {\t\t\t\ttext-align: center;\t\t\t\tfont-size: 12px;\t\t\t\tfont-family: segoe ui;\t\t\t\tfont-weight: bold;\t\t\t\tcolor: #666666;\t\t\t\tmargin: 6px 0 4px;\t\t\t\tdisplay: block;      }      @media only screen and (max-width : 320px) {      #bwg_container1_0 #bwg_container2_0 .displaying-num_0 {     \t display: none;      }      }      #bwg_container1_0 #bwg_container2_0 .displaying-num_0 {\t\t\t\tfont-size: 12px;\t\t\t\tfont-family: segoe ui;\t\t\t\tfont-weight: bold;\t\t\t\tcolor: #666666;\t\t\t\tmargin-right: 10px;\t\t\t\tvertical-align: middle;      }      #bwg_container1_0 #bwg_container2_0 .paging-input_0 {\t\t\t\tfont-size: 12px;\t\t\t\tfont-family: segoe ui;\t\t\t\tfont-weight: bold;\t\t\t\tcolor: #666666;\t\t\t\tvertical-align: middle;      }      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 a.disabled,      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 a.disabled:hover,      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 a.disabled:focus,\t\t\t#bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 input.bwg_current_page {\t\t\t\tcursor: default;\t\t\t\tcolor: rgba(102, 102, 102, 0.5);      }      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 a,      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 input.bwg_current_page {\t\t\t\tcursor: pointer;\t\t\t\ttext-align: center;\t\t\t\tfont-size: 12px;\t\t\t\tfont-family: segoe ui;\t\t\t\tfont-weight: bold;\t\t\t\tcolor: #666666;\t\t\t\ttext-decoration: none;\t\t\t\tpadding: 3px 6px;\t\t\t\tmargin: 0;\t\t\t\tborder-radius: 0;\t\t\t\tborder-style: solid;\t\t\t\tborder-width: 1px;\t\t\t\tborder-color: #E3E3E3;\t\t\t\t\t\t\t\tbackground-color: rgba(255, 255, 255, 1.00);\t\t\t\tbox-shadow: 0;\t\t\t\ttransition: all 0.3s ease 0s;-webkit-transition: all 0.3s ease 0s;      }      <\/style>      <span class=\"bwg_nav_cont_0\">              <div class=\"tablenav-pages_0\">                      <span class=\"pagination-links_0 pagination-links\" data-pages-count=\"2\">              <span class=\"pagination-links_col1\">              <a class=\"bwg-a first-page disabled\" title=\"Zur ersten Seite\" >\u00ab<\/a>              <a class=\"bwg-a prev-page disabled\" title=\"Zur vorherigen Seite\" >\u2039<\/a>              <\/span>\t\t\t\t\t\t\t<span class=\"pagination-links_col2\">\t\t\t\t\t\t\t\t\t<input type=\"number\" class=\"bwg_current_page\" name=\"bwg_current_page\" value=\"1\" data-url-info=\"page_number_0\" onkeypress=\"return bwg_change_page_0(event, this)\" min=\"1\" oninput=\"validity.valid||(value='')\" \/>\t\t\t\t\t\t\t\t\t\tvon\t\t\t\t\t\t\t\t\t\t<span class=\"total-pages_0\">\t\t\t\t\t\t\t\t\t\t\t2\t\t\t\t\t\t\t\t\t\t<\/span>\t\t\t\t\t\t\t<\/span>              <span class=\"pagination-links_col3\">                <a class=\"bwg-a next-page-0\" title=\"Zur n\u00e4chsten Seite\" href=\"\/wordpress\/wp-json\/wp\/v2\/posts\/3530?page_number_0=2\">\u203a<\/a>                <a class=\"bwg-a last-page-0\" title=\"Zur letzten Seite\" href=\"\/wordpress\/wp-json\/wp\/v2\/posts\/3530?page_number_0=2\">\u00bb<\/a>              <\/span>\t\t\t\t\t\t<\/span>\t\t\t\t\t\t        <\/div>                <input type=\"hidden\" id=\"page_number_0\" name=\"page_number_0\" value=\"1\" \/>      <script type=\"text\/javascript\">        if( jQuery('.bwg_nav_cont_0').length > 1 ) {          jQuery('.bwg_nav_cont_0').first().remove()        }        function spider_page_0(cur, x, y, load_more) {          if (typeof load_more == \"undefined\") {            var load_more = false;          }          if (jQuery(cur).hasClass('disabled')) {            return false;          }          var items_county_0 = 2;          switch (y) {            case 1:              if (x >= items_county_0) {                document.getElementById('page_number_0').value = items_county_0;              }              else {                document.getElementById('page_number_0').value = x + 1;              }              break;            case 2:              document.getElementById('page_number_0').value = items_county_0;              break;            case -1:              if (x == 1) {                document.getElementById('page_number_0').value = 1;              }              else {                document.getElementById('page_number_0').value = x - 1;              }              break;            case -2:              document.getElementById('page_number_0').value = 1;              break;\t\t\t\t\t\tcase 0:              document.getElementById('page_number_0').value = x;              break;            default:              document.getElementById('page_number_0').value = 1;          }          bwg_ajax('gal_front_form_0', '0', 'bwg_thumbnails_0', '0', '', 'gallery', 0, '', '', load_more, '', 1);        }                    jQuery('.first-page disabled').on('click', function () {              spider_page_0(this, 1, -2, 'numeric');              return false;            });            jQuery('.prev-page disabled').on('click', function () {              spider_page_0(this, 1, -1, 'numeric');              return false;            });            jQuery('.next-page-0').on('click', function () {              spider_page_0(this, 1, 1, 'numeric');              return false;            });            jQuery('.last-page-0').on('click', function () {              spider_page_0(this, 1, 2, 'numeric');              return false;            });        \t\t\t\t\/* Change page on input enter. *\/        function bwg_change_page_0( e, that ) {          if (  e.key == 'Enter' ) {            var to_page = parseInt(jQuery(that).val());            var pages_count = jQuery(that).parents(\".pagination-links\").data(\"pages-count\");            var current_url_param = jQuery(that).attr('data-url-info');            if (to_page > pages_count) {              to_page = 1;            }\t \t\t\t\t\t\t\t\t\t\t\t\tspider_page_0(this, to_page, 0, 'numeric');\t\t\t\t\t\t\treturn false;\t\t\t\t\t\t          }          return true;        }        jQuery('.bwg_load_btn_0').on('click', function () {            spider_page_0(this, 1, 1, true);            return false;        });      <\/script>      <\/span>                <\/div>        <\/form>        <style>          #bwg_container1_0 #bwg_container2_0 #spider_popup_overlay_0 {          background-color: #000000;          opacity: 0.70;          }          <\/style>        <div id=\"bwg_spider_popup_loading_0\" class=\"bwg_spider_popup_loading\"><\/div>        <div id=\"spider_popup_overlay_0\" class=\"spider_popup_overlay\" onclick=\"spider_destroypopup(1000)\"><\/div>        <input type=\"hidden\" id=\"bwg_random_seed_0\" value=\"1973417440\">                <\/div>    <\/div>    <script>      if (document.readyState === 'complete') {        if( typeof bwg_main_ready == 'function' ) {          if ( jQuery(\"#bwg_container1_0\").height() ) {            bwg_main_ready(jQuery(\"#bwg_container1_0\"));          }        }      } else {        document.addEventListener('DOMContentLoaded', function() {          if( typeof bwg_main_ready == 'function' ) {            if ( jQuery(\"#bwg_container1_0\").height() ) {             bwg_main_ready(jQuery(\"#bwg_container1_0\"));            }          }        });      }    <\/script>    \n","protected":false},"excerpt":{"rendered":"<p>Nachdem die Sch\u00fclerinnen und Sch\u00fcler der Klassen 7B und 7C den K\u00fcnstler Alberto Giacometti und seine Arbeiten kennenglernt hatten, machten sie sich selbst ans Werk.\u00a0Es<a class=\"moretag\" href=\"https:\/\/max-emden.de\/wordpress\/giacometti-meets-gips\/\"> [&#8230;]<\/a><\/p>\n","protected":false},"author":1,"featured_media":3531,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[37],"tags":[],"class_list":["post-3530","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kunst"],"_links":{"self":[{"href":"https:\/\/max-emden.de\/wordpress\/wp-json\/wp\/v2\/posts\/3530","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/max-emden.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/max-emden.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/max-emden.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/max-emden.de\/wordpress\/wp-json\/wp\/v2\/comments?post=3530"}],"version-history":[{"count":3,"href":"https:\/\/max-emden.de\/wordpress\/wp-json\/wp\/v2\/posts\/3530\/revisions"}],"predecessor-version":[{"id":3604,"href":"https:\/\/max-emden.de\/wordpress\/wp-json\/wp\/v2\/posts\/3530\/revisions\/3604"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/max-emden.de\/wordpress\/wp-json\/wp\/v2\/media\/3531"}],"wp:attachment":[{"href":"https:\/\/max-emden.de\/wordpress\/wp-json\/wp\/v2\/media?parent=3530"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/max-emden.de\/wordpress\/wp-json\/wp\/v2\/categories?post=3530"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/max-emden.de\/wordpress\/wp-json\/wp\/v2\/tags?post=3530"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}